{"id":391,"date":"2024-02-27T07:14:13","date_gmt":"2024-02-27T06:14:13","guid":{"rendered":"https:\/\/agrion-risle-charentonne.fr\/?p=391"},"modified":"2024-02-27T07:14:15","modified_gmt":"2024-02-27T06:14:15","slug":"sortie-du-25-fevrier-au-lac-de-brionne","status":"publish","type":"post","link":"https:\/\/agrion-risle-charentonne.fr\/index.php\/2024\/02\/27\/sortie-du-25-fevrier-au-lac-de-brionne\/","title":{"rendered":"Sortie du 25 f\u00e9vrier au lac de Brionne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s la conf\u00e9rence de vendredi sur les oiseaux hivernants, nos membres se sont retrouv\u00e9s au lac de Brionne ce dimanche pour une sortie nature.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 une m\u00e9t\u00e9o peu engageante, nous avons pu observer quelques hivernants typiques. Tr\u00e8s rapidement nous avons pu localiser les incontournables <strong>tarins des aulnes<\/strong> virevoltant d\u2019arbre en arbre en bandes assez compactes \u00e0 la recherche de graines. Sur le plan d\u2019eau, seul un couple de <strong>fuligules<\/strong> <strong>morillons<\/strong> t\u00e9moignait de la pr\u00e9sence encore r\u00e9cente des canards venus du grand nord. Ce couple isol\u00e9 fera peut-\u00eatre partie des rares couples nicheurs de Normandie. Ce couple partageait le site avec des <strong>gr\u00e8bes hupp\u00e9s<\/strong> qui nous ont gratifi\u00e9 d\u2019une \u00e9bauche de parade nuptiale, de quelques <strong>foulques<\/strong> <strong>macroules <\/strong>et<strong> gallinules poules d\u2019eau<\/strong> toujours tr\u00e8s d\u00e9licates. Beaucoup moins discr\u00e8tes et tr\u00e8s vindicatives un groupe de <strong>bernaches du Canada<\/strong> occupait avec autorit\u00e9 l\u2019\u00eelot. La rigueur de l\u2019hiver n\u2019\u00e9tant plus de mise, nous avons pu appr\u00e9cier les premiers chants du <strong>pinson des arbres, du verdier<\/strong>, <strong>du troglodyte et du chardonneret \u00e9l\u00e9gant<\/strong>. Ce fut l\u2019occasion de tester les performances de l\u2019application Merlin Bird capable apr\u00e8s analyse de d\u00e9terminer l\u2019oiseau chanteur. Nous avons pu \u00e9galement d\u00e9tailler le plumage d\u00e9licat des <strong>bergeronnettes grises et des chardonnerets<\/strong>. Quelle que soit la saison, ce site apaisant offre toujours de belles surprises\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1-1024x768.jpg\" alt=\"\" class=\"wp-image-392\" srcset=\"https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1-1024x768.jpg 1024w, https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1-300x225.jpg 300w, https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1-768x576.jpg 768w, https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1-1200x900.jpg 1200w, https:\/\/agrion-risle-charentonne.fr\/wp-content\/uploads\/2024\/02\/Image1.jpg 1386w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Photo : Val\u00e9rie Bruneau-Querey<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s la conf\u00e9rence de vendredi sur les oiseaux hivernants, nos membres se sont retrouv\u00e9s au lac de Brionne ce dimanche pour une sortie nature. Malgr\u00e9 une m\u00e9t\u00e9o peu engageante, nous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":392,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/template-cover.php","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1,6],"tags":[25,15],"class_list":["post-391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association-agrion","category-evenements","tag-merlin-bird","tag-valerie-bruneau-querey"],"_links":{"self":[{"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/posts\/391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":1,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/posts\/391\/revisions"}],"predecessor-version":[{"id":393,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/posts\/391\/revisions\/393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/media\/392"}],"wp:attachment":[{"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrion-risle-charentonne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}